{"id":2792,"count":2,"description":"","link":"https:\/\/telugucinema.com\/telugu\/tag\/%e0%b0%aa%e0%b1%8d%e0%b0%b0%e0%b0%ad%e0%b0%be%e0%b0%b8%e0%b1%8d-%e0%b0%ae%e0%b1%82%e0%b0%b5%e0%b1%80%e0%b0%b8%e0%b1%8d","name":"\u0c2a\u0c4d\u0c30\u0c2d\u0c3e\u0c38\u0c4d \u0c2e\u0c42\u0c35\u0c40\u0c38\u0c4d","slug":"%e0%b0%aa%e0%b1%8d%e0%b0%b0%e0%b0%ad%e0%b0%be%e0%b0%b8%e0%b1%8d-%e0%b0%ae%e0%b1%82%e0%b0%b5%e0%b1%80%e0%b0%b8%e0%b1%8d","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/telugucinema.com\/telugu\/wp-json\/wp\/v2\/tags\/2792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/telugucinema.com\/telugu\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/telugucinema.com\/telugu\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/telugucinema.com\/telugu\/wp-json\/wp\/v2\/posts?tags=2792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}